{"id":86412,"date":"2026-03-28T10:20:40","date_gmt":"2026-03-28T09:20:40","guid":{"rendered":"https:\/\/www.demosmobilia.ch\/product\/table-basse-art-deco-italienne-en-noyer-poli\/"},"modified":"2026-03-28T10:20:40","modified_gmt":"2026-03-28T09:20:40","slug":"table-basse-art-deco-italienne-en-noyer-poli","status":"publish","type":"product","link":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/","title":{"rendered":"Table basse Art d\u00e9co italienne en noyer poli"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><a class=\"more-link\" href=\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/\">Read More &rarr;<\/a><\/p>\n","protected":false},"featured_media":86397,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":""},"product_cat":[4071,4276],"product_tag":[7111],"class_list":{"0":"entry","1":"author-demosmobilia","2":"post-86412","3":"product","4":"type-product","5":"status-publish","6":"has-post-thumbnail","7":"product_production-italian-production","8":"product_year-1930-approx","9":"product_nation-italie-fr","10":"product_cat-nouveautes","11":"product_cat-tables-basses","12":"product_tag-italian-design-fr","13":"pa_product_dimension-dia-78-x-ht-45-cm","14":"pa_product_material-noyer","16":"first","17":"instock","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Table basse Art d\u00e9co italienne en noyer poli &#8211; Demosmobilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Table basse Art d\u00e9co italienne en noyer poli &#8211; Demosmobilia\" \/>\n<meta property=\"og:description\" content=\"Read More &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/\" \/>\n<meta property=\"og:site_name\" content=\"Demosmobilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/\",\"url\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/\",\"name\":\"Table basse Art d\u00e9co italienne en noyer poli &#8211; Demosmobilia\",\"isPartOf\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-02.jpg\",\"datePublished\":\"2026-03-28T09:20:40+00:00\",\"dateModified\":\"2026-03-28T09:20:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#primaryimage\",\"url\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-02.jpg\",\"contentUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-02.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.demosmobilia.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/www.demosmobilia.ch\/fr\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Table basse Art d\u00e9co italienne en noyer poli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/#website\",\"url\":\"https:\/\/www.demosmobilia.ch\/fr\/\",\"name\":\"Demosmobilia\",\"description\":\"Vintage Mid Century Modern Design Furniture from the &#039;30s to the &#039;80s\",\"publisher\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.demosmobilia.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/#organization\",\"name\":\"demosmobilia\",\"url\":\"https:\/\/www.demosmobilia.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png\",\"contentUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png\",\"width\":230,\"height\":160,\"caption\":\"demosmobilia\"},\"image\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/\",\"https:\/\/www.instagram.com\/demosmobilia\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Table basse Art d\u00e9co italienne en noyer poli &#8211; Demosmobilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/","og_locale":"fr_FR","og_type":"article","og_title":"Table basse Art d\u00e9co italienne en noyer poli &#8211; Demosmobilia","og_description":"Read More &rarr;","og_url":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/","og_site_name":"Demosmobilia","article_publisher":"https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/","url":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/","name":"Table basse Art d\u00e9co italienne en noyer poli &#8211; Demosmobilia","isPartOf":{"@id":"https:\/\/www.demosmobilia.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#primaryimage"},"image":{"@id":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-02.jpg","datePublished":"2026-03-28T09:20:40+00:00","dateModified":"2026-03-28T09:20:40+00:00","breadcrumb":{"@id":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#primaryimage","url":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-02.jpg","contentUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2026\/03\/carlton-coffee-table-italian-art-deco-design-02.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.demosmobilia.ch\/fr\/product\/table-basse-art-deco-italienne-en-noyer-poli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.demosmobilia.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.demosmobilia.ch\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Table basse Art d\u00e9co italienne en noyer poli"}]},{"@type":"WebSite","@id":"https:\/\/www.demosmobilia.ch\/fr\/#website","url":"https:\/\/www.demosmobilia.ch\/fr\/","name":"Demosmobilia","description":"Vintage Mid Century Modern Design Furniture from the &#039;30s to the &#039;80s","publisher":{"@id":"https:\/\/www.demosmobilia.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.demosmobilia.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.demosmobilia.ch\/fr\/#organization","name":"demosmobilia","url":"https:\/\/www.demosmobilia.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.demosmobilia.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png","contentUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png","width":230,"height":160,"caption":"demosmobilia"},"image":{"@id":"https:\/\/www.demosmobilia.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/","https:\/\/www.instagram.com\/demosmobilia\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/product\/86412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/media\/86397"}],"wp:attachment":[{"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/media?parent=86412"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=86412"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=86412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}