{"id":51817,"date":"2021-05-29T13:50:12","date_gmt":"2021-05-29T11:50:12","guid":{"rendered":"https:\/\/www.demosmobilia.ch\/memphis-40-jahre-kitsch-und-eleganz\/"},"modified":"2021-05-29T13:50:13","modified_gmt":"2021-05-29T11:50:13","slug":"memphis-40-jahre-kitsch-und-eleganz","status":"publish","type":"post","link":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/","title":{"rendered":"Memphis: 40 Jahre Kitsch und Eleganz"},"content":{"rendered":"<p>06.02.2021 \u2013 23.01.2022<\/p><p>Vitra Design Museum Galerie<\/p><p>Die Memphis-Gruppe war eines der ungew\u00f6hnlichsten Ph\u00e4nomene, die in den letzten Jahrzehnten in der Welt des Designs auftraten. Sie entstand im Winter 1980\/81, als sich um den italienischen Architekten und Designer Ettore Sottsass eine Gruppe junger Designer formierte, die mit den Dogmen des Funktionalismus und des Industriedesigns brechen wollten. <\/p><!--more--><p>Die erste Kollektion der Gruppe, die im September 1981 in der Mail\u00e4nder Galerie Arc&#8217;74 pr\u00e4sentiert wurde, war eine internationale Sensation. Gepr\u00e4gt von schrillen Farben und wilden Mustern schienen die Memphis-Entw\u00fcrfe direkt aus einem Comic entsprungen zu sein und begr\u00fcndeten einen v\u00f6llig neuen Look, in dem Popul\u00e4rkultur, Werbe\u00e4sthetik und Postmoderne zu einem verr\u00fcckten Medley verschmolzen. Die Ausstellung &#8222;Memphis: 40 Years of Kitsch and Elegance&#8220; in der Vitra Design Museum Gallery feiert das vierzigj\u00e4hrige Bestehen der Gruppe anhand ihrer Kreationen und pr\u00e4sentiert M\u00f6bel, Lampen, Schalen, Zeichnungen, Skizzen und Fotografien, die einen Einblick in die Welt von Memphis geben. Zu sehen sind Arbeiten von so bekannten Mitgliedern wie Ettore Sottsass, Michele De Lucchi, Martine Bedin, Michael Graves, Barbara Radice, Peter Shire, Nathalie Du Pasquier und Shiro Kuramata.&#13;\n<\/p><p>Bild:&#13;\nDas Memphis-Team posiert auf dem Bett &#8222;Masanori&#8220; von Umeda Tawaraya, 1981&#13;\n\u00a9 Masanori Umeda&#13;\n\u00a9 Studio Azzurro, mit freundlicher Genehmigung von Memphis, Mailand, www.memphis-milano.com<\/p>","protected":false},"excerpt":{"rendered":"<p>06.02.2021 \u2013 23.01.2022 Vitra Design Museum Galerie Die Memphis-Gruppe war eines der ungew\u00f6hnlichsten Ph\u00e4nomene, die in den letzten Jahrzehnten in der Welt des Designs auftraten. Sie entstand im Winter 1980\/81, als sich um den italienischen Architekten und Designer Ettore Sottsass eine Gruppe junger Designer formierte, die mit den Dogmen des Funktionalismus und des Industriedesigns brechen wollten.<a class=\"more-link\" href=\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\">Read More &rarr;<\/a><\/p>\n","protected":false},"author":5,"featured_media":51811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":"","footnotes":""},"categories":[4203],"tags":[],"class_list":["entry","author-demosmobilia","has-more-link","post-51817","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ausstellungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Memphis: 40 Jahre Kitsch und Eleganz &#8211; demosmobilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Memphis: 40 Jahre Kitsch und Eleganz &#8211; demosmobilia\" \/>\n<meta property=\"og:description\" content=\"06.02.2021 \u2013 23.01.2022 Vitra Design Museum Galerie Die Memphis-Gruppe war eines der ungew\u00f6hnlichsten Ph\u00e4nomene, die in den letzten Jahrzehnten in der Welt des Designs auftraten. Sie entstand im Winter 1980\/81, als sich um den italienischen Architekten und Designer Ettore Sottsass eine Gruppe junger Designer formierte, die mit den Dogmen des Funktionalismus und des Industriedesigns brechen wollten.Read More &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\" \/>\n<meta property=\"og:site_name\" content=\"demosmobilia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-29T11:50:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-29T11:50:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1284\" \/>\n\t<meta property=\"og:image:height\" content=\"1418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"demosmobilia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"demosmobilia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\"},\"author\":{\"name\":\"demosmobilia\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/person\/351e191849023abe83b1fa617fbeb99c\"},\"headline\":\"Memphis: 40 Jahre Kitsch und Eleganz\",\"datePublished\":\"2021-05-29T11:50:12+00:00\",\"dateModified\":\"2021-05-29T11:50:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\"},\"wordCount\":217,\"publisher\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png\",\"articleSection\":[\"Ausstellungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\",\"url\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\",\"name\":\"Memphis: 40 Jahre Kitsch und Eleganz &#8211; demosmobilia\",\"isPartOf\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png\",\"datePublished\":\"2021-05-29T11:50:12+00:00\",\"dateModified\":\"2021-05-29T11:50:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage\",\"url\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png\",\"contentUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png\",\"width\":1284,\"height\":1418},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.demosmobilia.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Memphis: 40 Jahre Kitsch und Eleganz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#website\",\"url\":\"https:\/\/www.demosmobilia.ch\/de\/\",\"name\":\"demosmobilia\",\"description\":\"Vintage Mid Century Modern Design Furniture from the &#039;30s to the &#039;80s\",\"publisher\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.demosmobilia.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#organization\",\"name\":\"demosmobilia\",\"url\":\"https:\/\/www.demosmobilia.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png\",\"contentUrl\":\"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png\",\"width\":230,\"height\":160,\"caption\":\"demosmobilia\"},\"image\":{\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/\",\"https:\/\/www.instagram.com\/demosmobilia\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/person\/351e191849023abe83b1fa617fbeb99c\",\"name\":\"demosmobilia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/827af99f347ba98a7d30a2b7f0f4949413c4aa208a7be01a586b3b24bd99a016?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/827af99f347ba98a7d30a2b7f0f4949413c4aa208a7be01a586b3b24bd99a016?s=96&d=mm&r=g\",\"caption\":\"demosmobilia\"},\"url\":\"https:\/\/www.demosmobilia.ch\/de\/author\/demosmobilia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Memphis: 40 Jahre Kitsch und Eleganz &#8211; demosmobilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/","og_locale":"de_DE","og_type":"article","og_title":"Memphis: 40 Jahre Kitsch und Eleganz &#8211; demosmobilia","og_description":"06.02.2021 \u2013 23.01.2022 Vitra Design Museum Galerie Die Memphis-Gruppe war eines der ungew\u00f6hnlichsten Ph\u00e4nomene, die in den letzten Jahrzehnten in der Welt des Designs auftraten. Sie entstand im Winter 1980\/81, als sich um den italienischen Architekten und Designer Ettore Sottsass eine Gruppe junger Designer formierte, die mit den Dogmen des Funktionalismus und des Industriedesigns brechen wollten.Read More &rarr;","og_url":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/","og_site_name":"demosmobilia","article_publisher":"https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/","article_published_time":"2021-05-29T11:50:12+00:00","article_modified_time":"2021-05-29T11:50:13+00:00","og_image":[{"width":1284,"height":1418,"url":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png","type":"image\/png"}],"author":"demosmobilia","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"demosmobilia","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#article","isPartOf":{"@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/"},"author":{"name":"demosmobilia","@id":"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/person\/351e191849023abe83b1fa617fbeb99c"},"headline":"Memphis: 40 Jahre Kitsch und Eleganz","datePublished":"2021-05-29T11:50:12+00:00","dateModified":"2021-05-29T11:50:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/"},"wordCount":217,"publisher":{"@id":"https:\/\/www.demosmobilia.ch\/de\/#organization"},"image":{"@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png","articleSection":["Ausstellungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/","url":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/","name":"Memphis: 40 Jahre Kitsch und Eleganz &#8211; demosmobilia","isPartOf":{"@id":"https:\/\/www.demosmobilia.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage"},"image":{"@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png","datePublished":"2021-05-29T11:50:12+00:00","dateModified":"2021-05-29T11:50:13+00:00","breadcrumb":{"@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#primaryimage","url":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png","contentUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2021\/05\/memphis-design.png","width":1284,"height":1418},{"@type":"BreadcrumbList","@id":"https:\/\/www.demosmobilia.ch\/de\/memphis-40-jahre-kitsch-und-eleganz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.demosmobilia.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Memphis: 40 Jahre Kitsch und Eleganz"}]},{"@type":"WebSite","@id":"https:\/\/www.demosmobilia.ch\/de\/#website","url":"https:\/\/www.demosmobilia.ch\/de\/","name":"demosmobilia","description":"Vintage Mid Century Modern Design Furniture from the &#039;30s to the &#039;80s","publisher":{"@id":"https:\/\/www.demosmobilia.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.demosmobilia.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.demosmobilia.ch\/de\/#organization","name":"demosmobilia","url":"https:\/\/www.demosmobilia.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png","contentUrl":"https:\/\/www.demosmobilia.ch\/wp-content\/uploads\/2020\/07\/demosmobilia-logo-2020-230-160.png","width":230,"height":160,"caption":"demosmobilia"},"image":{"@id":"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Demos-Mobilia-1137017453131445\/","https:\/\/www.instagram.com\/demosmobilia\/"]},{"@type":"Person","@id":"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/person\/351e191849023abe83b1fa617fbeb99c","name":"demosmobilia","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.demosmobilia.ch\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/827af99f347ba98a7d30a2b7f0f4949413c4aa208a7be01a586b3b24bd99a016?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/827af99f347ba98a7d30a2b7f0f4949413c4aa208a7be01a586b3b24bd99a016?s=96&d=mm&r=g","caption":"demosmobilia"},"url":"https:\/\/www.demosmobilia.ch\/de\/author\/demosmobilia\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/posts\/51817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/comments?post=51817"}],"version-history":[{"count":1,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/posts\/51817\/revisions"}],"predecessor-version":[{"id":51818,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/posts\/51817\/revisions\/51818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/media\/51811"}],"wp:attachment":[{"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/media?parent=51817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/categories?post=51817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.demosmobilia.ch\/de\/wp-json\/wp\/v2\/tags?post=51817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}